{"id":2208,"date":"2025-02-18T13:25:22","date_gmt":"2025-02-18T13:25:22","guid":{"rendered":"https:\/\/www.freelance.co.uk\/blog\/wp-content\/uploads\/2025\/02\/SEO-Types-of-search-intents.webp"},"modified":"2025-02-18T13:25:39","modified_gmt":"2025-02-18T13:25:39","slug":"seo-types-of-search-intents","status":"inherit","type":"attachment","link":"https:\/\/www.freelance.co.uk\/blog\/what-does-an-seo-freelancer-really-do-an-inside-look\/seo-types-of-search-intents\/","title":{"rendered":"SEO-Types-of-search-intents"},"author":11,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-2208","attachment","type-attachment","status-inherit","hentry","excerpt"],"aioseo_notices":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.freelance.co.uk\/blog\/wp-content\/uploads\/2025\/02\/SEO-Types-of-search-intents.webp'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"150\" src=\"https:\/\/www.freelance.co.uk\/blog\/wp-content\/uploads\/2025\/02\/SEO-Types-of-search-intents-300x150.webp\" class=\"attachment-medium size-medium\" alt=\"Different types of search intents\" srcset=\"https:\/\/www.freelance.co.uk\/blog\/wp-content\/uploads\/2025\/02\/SEO-Types-of-search-intents-300x150.webp 300w, https:\/\/www.freelance.co.uk\/blog\/wp-content\/uploads\/2025\/02\/SEO-Types-of-search-intents-1024x512.webp 1024w, https:\/\/www.freelance.co.uk\/blog\/wp-content\/uploads\/2025\/02\/SEO-Types-of-search-intents-768x384.webp 768w, https:\/\/www.freelance.co.uk\/blog\/wp-content\/uploads\/2025\/02\/SEO-Types-of-search-intents-1536x768.webp 1536w, https:\/\/www.freelance.co.uk\/blog\/wp-content\/uploads\/2025\/02\/SEO-Types-of-search-intents-2048x1024.webp 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Different types of search intents","media_type":"image","mime_type":"image\/webp","media_details":{"width":2400,"height":1200,"file":"2025\/02\/SEO-Types-of-search-intents.webp","filesize":69458,"sizes":{"medium":{"file":"SEO-Types-of-search-intents-300x150.webp","width":300,"height":150,"filesize":5178,"mime_type":"image\/webp","source_url":"https:\/\/www.freelance.co.uk\/blog\/wp-content\/uploads\/2025\/02\/SEO-Types-of-search-intents-300x150.webp"},"large":{"file":"SEO-Types-of-search-intents-1024x512.webp","width":1024,"height":512,"filesize":25564,"mime_type":"image\/webp","source_url":"https:\/\/www.freelance.co.uk\/blog\/wp-content\/uploads\/2025\/02\/SEO-Types-of-search-intents-1024x512.webp"},"thumbnail":{"file":"SEO-Types-of-search-intents-900x500.webp","width":900,"height":500,"filesize":24200,"mime_type":"image\/webp","source_url":"https:\/\/www.freelance.co.uk\/blog\/wp-content\/uploads\/2025\/02\/SEO-Types-of-search-intents-900x500.webp"},"medium_large":{"file":"SEO-Types-of-search-intents-768x384.webp","width":768,"height":384,"filesize":18076,"mime_type":"image\/webp","source_url":"https:\/\/www.freelance.co.uk\/blog\/wp-content\/uploads\/2025\/02\/SEO-Types-of-search-intents-768x384.webp"},"1536x1536":{"file":"SEO-Types-of-search-intents-1536x768.webp","width":1536,"height":768,"filesize":40328,"mime_type":"image\/webp","source_url":"https:\/\/www.freelance.co.uk\/blog\/wp-content\/uploads\/2025\/02\/SEO-Types-of-search-intents-1536x768.webp"},"2048x2048":{"file":"SEO-Types-of-search-intents-2048x1024.webp","width":2048,"height":1024,"filesize":56306,"mime_type":"image\/webp","source_url":"https:\/\/www.freelance.co.uk\/blog\/wp-content\/uploads\/2025\/02\/SEO-Types-of-search-intents-2048x1024.webp"},"profile_24":{"file":"SEO-Types-of-search-intents-24x24.webp","width":24,"height":24,"filesize":330,"mime_type":"image\/webp","source_url":"https:\/\/www.freelance.co.uk\/blog\/wp-content\/uploads\/2025\/02\/SEO-Types-of-search-intents-24x24.webp"},"profile_48":{"file":"SEO-Types-of-search-intents-48x48.webp","width":48,"height":48,"filesize":762,"mime_type":"image\/webp","source_url":"https:\/\/www.freelance.co.uk\/blog\/wp-content\/uploads\/2025\/02\/SEO-Types-of-search-intents-48x48.webp"},"profile_96":{"file":"SEO-Types-of-search-intents-96x96.webp","width":96,"height":96,"filesize":1924,"mime_type":"image\/webp","source_url":"https:\/\/www.freelance.co.uk\/blog\/wp-content\/uploads\/2025\/02\/SEO-Types-of-search-intents-96x96.webp"},"profile_150":{"file":"SEO-Types-of-search-intents-150x150.webp","width":150,"height":150,"filesize":3728,"mime_type":"image\/webp","source_url":"https:\/\/www.freelance.co.uk\/blog\/wp-content\/uploads\/2025\/02\/SEO-Types-of-search-intents-150x150.webp"},"profile_300":{"file":"SEO-Types-of-search-intents-300x300.webp","width":300,"height":300,"filesize":9630,"mime_type":"image\/webp","source_url":"https:\/\/www.freelance.co.uk\/blog\/wp-content\/uploads\/2025\/02\/SEO-Types-of-search-intents-300x300.webp"},"full":{"file":"SEO-Types-of-search-intents.webp","width":2400,"height":1200,"mime_type":"image\/webp","source_url":"https:\/\/www.freelance.co.uk\/blog\/wp-content\/uploads\/2025\/02\/SEO-Types-of-search-intents.webp"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":2191,"source_url":"https:\/\/www.freelance.co.uk\/blog\/wp-content\/uploads\/2025\/02\/SEO-Types-of-search-intents.webp","_links":{"self":[{"href":"https:\/\/www.freelance.co.uk\/blog\/wp-json\/wp\/v2\/media\/2208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.freelance.co.uk\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.freelance.co.uk\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.freelance.co.uk\/blog\/wp-json\/wp\/v2\/users\/11"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":2191,"href":"https:\/\/www.freelance.co.uk\/blog\/wp-json\/wp\/v2\/posts\/2191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}